{"id":79,"date":"2015-06-23T16:08:14","date_gmt":"2015-06-23T14:08:14","guid":{"rendered":"http:\/\/tsvschott.de\/fussball\/?p=79"},"modified":"2015-06-23T16:08:14","modified_gmt":"2015-06-23T14:08:14","slug":"testpost-1-alte-herren","status":"publish","type":"post","link":"https:\/\/tsvschott.de\/kindersport-akademie\/2015\/06\/23\/testpost-1-alte-herren\/","title":{"rendered":"Testpost 1 Alte Herren"},"content":{"rendered":"<p>Testpost 1 Alte Herren<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Testpost 1 Alte Herren<\/p>\n","protected":false},"author":44,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-79","post","type-post","status-publish","format-standard","hentry","category-alte-herren"],"_links":{"self":[{"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/posts\/79","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/comments?post=79"}],"version-history":[{"count":0,"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/posts\/79\/revisions"}],"wp:attachment":[{"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/media?parent=79"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/categories?post=79"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsvschott.de\/kindersport-akademie\/wp-json\/wp\/v2\/tags?post=79"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}